{"id":281,"date":"2015-06-25T12:43:18","date_gmt":"2015-06-25T17:13:18","guid":{"rendered":"http:\/\/controlreal.com\/es\/?p=281"},"modified":"2019-05-18T18:01:52","modified_gmt":"2019-05-18T22:31:52","slug":"planos-electricos-lectura-interpretacion","status":"publish","type":"post","link":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/","title":{"rendered":"Planos El\u00e9ctricos. Lectura e interpretaci\u00f3n."},"content":{"rendered":"<p style=\"text-align: justify;\">En los diagramas o planos el\u00e9ctricos se representan de forma gr\u00e1fica los componentes, y su interconexi\u00f3n, en una instalaci\u00f3n el\u00e9ctrica. El uso de planos el\u00e9ctricos est\u00e1 basado en est\u00e1ndares creados por diferentes organizaciones internacionales. Su uso permite la construcci\u00f3n y mantenimiento de los sistemas el\u00e9ctricos, adem\u00e1s de representar el funcionamiento de los mismos.<\/p>\n<p>Existen varias clases de diagramas que nos ayudan a comprender el funcionamiento de un sistema. Entre ellos tenemos:<\/p>\n<ul>\n<li><a href=\"https:\/\/controlreal.com\/es\/diagramas-de-tuberias-e-instrumentacion-pid\/\" target=\"_blank\" rel=\"noopener\">Diagramas de tuber\u00edas e instrumentaci\u00f3n (P&amp;ID)<\/a> que nos muestran la interconexi\u00f3n de los equipos, nos dan una idea de c\u00f3mo fluye el material y la interconexi\u00f3n de las se\u00f1ales, neum\u00e1tica, el\u00e9ctricas, electromagn\u00e9ticas hidr\u00e1ulicas entre otras.<\/li>\n<li>Diagramas de lazos: que nos muestran en cada plano los elementos involucrados en un lazo de control.<\/li>\n<li>Diagramas l\u00f3gicos. Que muestran el funcionamiento de sistemas binarios para se\u00f1ales el\u00e9ctricas, electr\u00f3nicas, mec\u00e1nicas, neum\u00e1ticas, hidr\u00e1ulicas, manuales entre otras.<\/li>\n<li>Diagramas unifilares. Se indica por medio de l\u00edneas sencillas y s\u00edmbolos simplificados, la interconexi\u00f3n y partes (componentes) de un circuito o sistema el\u00e9ctrico.<\/li>\n<li>Los Diagramas electr\u00f3nicos. Muestran la interconexi\u00f3n de los elementos electr\u00f3nicos en un circuito impreso.<\/li>\n<li>Diagramas elementales. Muestran la interconexi\u00f3n el\u00e9ctrica de los dispositivos el\u00e9ctricos y electr\u00f3nicos de un sistema.<\/li>\n<\/ul>\n<p>En este articulo se ver\u00e1n los diagramas elementales que son los m\u00e1s comunes y los m\u00e1s utilizados en el mantenimiento de los sistemas el\u00e9ctricos y de control.<\/p>\n<h2><strong>Organismos de estandarizaci\u00f3n.<\/strong><\/h2>\n<p style=\"text-align: justify;\">Para garantizar un correcto flujo de informaci\u00f3n y facilitar la lectura de planos el\u00e9ctricos se han dise\u00f1ados diversos organismos de estandarizaci\u00f3n y normativas a nivel mundial dentro de los cuales destacan:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.google.co.ve\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=1&amp;cad=rja&amp;uact=8&amp;ved=0CBwQFjAA&amp;url=http%3A%2F%2Fwww.ansi.org%2F&amp;ei=5zGMVdmeC4Gw-QGYrIK4Aw&amp;usg=AFQjCNHLxTPJlhFJewMyrYweTOzQAS17PA&amp;sig2=TZbdrMH5uYWjrQMLOkNQgA&amp;bvm=bv.96782255,d.cWw\" target=\"_blank\" rel=\"noopener noreferrer\">American National Standards Institute (ANSI)<\/a><\/li>\n<li><a href=\"https:\/\/www.google.co.ve\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=1&amp;cad=rja&amp;uact=8&amp;ved=0CBwQFjAA&amp;url=http%3A%2F%2Fwww.din.de%2Fen&amp;ei=_jGMVdLlKoPo-QHpvrzYDw&amp;usg=AFQjCNEUX-k_nw3rZGTx0KbM_CIjyTtrOg&amp;sig2=ZtoGo1Kp9jObtqOPKzQZew&amp;bvm=bv.96782255,d.cWw\" target=\"_blank\" rel=\"noopener noreferrer\">Deutsches Institut f\u00fcr Normung (DIN)<\/a><\/li>\n<li><a href=\"https:\/\/www.google.co.ve\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=1&amp;cad=rja&amp;uact=8&amp;ved=0CBwQFjAA&amp;url=http%3A%2F%2Fwww.iso.org%2F&amp;ei=NTKMVe-JM4z0-AGQlIPQAw&amp;usg=AFQjCNGpo76kUCYLHRrJE75GAgqvqEcs1A&amp;sig2=AAZiwhOCnWBDMjwVHZcgmg&amp;bvm=bv.96782255,d.cWw\" target=\"_blank\" rel=\"noopener noreferrer\">Organizaci\u00f3n Internacional para la Estandarizaci\u00f3n (ISO)<\/a><\/li>\n<li><a href=\"https:\/\/www.google.co.ve\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=1&amp;cad=rja&amp;uact=8&amp;ved=0CB0QFjAA&amp;url=http%3A%2F%2Fwww.iec.ch%2F&amp;ei=qTGMVcqGLYHw-AGZuIDAAg&amp;usg=AFQjCNGBHN3do4Q3AKC0BbWsopS18dcMCg&amp;sig2=B0Alj-lHL__M7opa99s9BA&amp;bvm=bv.96782255,d.cWw\" target=\"_blank\" rel=\"noopener noreferrer\">Comisi\u00f3n Electrot\u00e9cnica Internacional (IEC)<\/a><\/li>\n<li><a href=\"https:\/\/www.google.co.ve\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=1&amp;cad=rja&amp;uact=8&amp;ved=0CBwQFjAA&amp;url=http%3A%2F%2Fwww.nema.org%2F&amp;ei=GTKMVZ7xL8qz-QHcmI6wAw&amp;usg=AFQjCNF4Glb3YCbmctFgJ79MCAQ-1sAXTQ&amp;sig2=Jzf9zerJF5Hfhn-tukLIKg&amp;bvm=bv.96782255,d.cWw\" target=\"_blank\" rel=\"noopener noreferrer\">Asociaci\u00f3n Norteamericana de Manufacturas El\u00e9ctricas (NEMA)<\/a><\/li>\n<\/ul>\n<h2><strong>S\u00edmbolos<\/strong><\/h2>\n<p style=\"text-align: justify;\">Es la representaci\u00f3n gr\u00e1fica de un elemento f\u00edsico, presente en los planos el\u00e9ctricos, como por ejemplo un rel\u00e9, un arrancador o un transformador entre otros. Existen diferentes s\u00edmbolos para el mismo dispositivo seg\u00fan la norma que se est\u00e9 usando para desarrollar el plano el\u00e9ctrico. <span style=\"color: #0000ff;\"><a href=\"https:\/\/controlreal.com\/es\/simbolos-electricos\/\">Aqu\u00ed<\/a><\/span> se muestran diferentes s\u00edmbolos para las normas DIN, ANSI e IEC.<\/p>\n<h2><strong>Nomenclatura<\/strong><\/h2>\n<p style=\"text-align: justify;\">En los planos el\u00e9ctricos a cada s\u00edmbolo se le asocia un nombre con el cual se va a conocer al dispositivo dentro del conjunto de planos, en otros documentos asociados al sistema y en el propio dispositivo una vez que es instalado en campo. Hay muchas formas de escoger el nombre y depende del dise\u00f1ador, se explicar\u00e1n dos maneras de uso muy frecuente.<\/p>\n<p>Forma 1: el nombre para el s\u00edmbolo est\u00e1 formado por dos partes, la clase y el n\u00famero. Por ejemplo en las siglas Q3 la Q se refiere a un interruptor de protecci\u00f3n, el n\u00famero 3 se usa para distinguir en caso de que existan varias protecciones. Es frecuente combinar m\u00e1s de una letra para la clase, por ejemplo la letra K se refiere a un rel\u00e9 o a un contactor (arrancador), si la combinamos con la M entonces KM se refiere al contactor (arrancador) de un motor. Seg\u00fan la norma IEC750 el nombre debe comenzar con un gui\u00f3n, por ejemplo \u2013Q3A.<\/p>\n<p>Forma 2: el nombre para el s\u00edmbolo est\u00e1 formado por tres partes, el n\u00famero del plano, la clase y la ubicaci\u00f3n en el plano. Por ejemplo 1Q15 se refiere a un interruptor de protecci\u00f3n que se encuentra en el plano 1, franja 15 (los planos suelen dividirse en franjas o cuadrantes que facilitan la <span style=\"color: #0000ff;\"><a href=\"https:\/\/controlreal.com\/es\/referencia-cruzada\/\">ubicaci\u00f3n de los elementos<\/a><\/span>). En una variante de esta forma, la ubicaci\u00f3n en el plano suele cambiarse por n\u00fameros consecutivos por ejemplo si en el plano 1 hay dos interruptores de\u00a0 protecci\u00f3n sus nombres ser\u00edan 1Q1 y 1Q2.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><a href=\"https:\/\/controlreal.com\/es\/nomenclatura-de-planos-electricos\/\">Aqu\u00ed<\/a><\/span> se encuentra la tabla para las letras que se usan en la clase.<\/p>\n<h2><strong>Tipos de planos El\u00e9ctricos.<\/strong><\/h2>\n<p style=\"text-align: justify;\">Los planos el\u00e9ctricos describen diferentes aspectos de los sistemas y en general agrupan elementos relacionados o similares. Podemos encontrar los siguientes tipos de planos en un mismo conjunto.<\/p>\n<ol>\n<li>Alimentaci\u00f3n General.<\/li>\n<li>Potencia.<\/li>\n<li>Mando.<\/li>\n<li>Entrada y salidas.<\/li>\n<li>Alimentaci\u00f3n de dispositivos.<\/li>\n<li>Borneras.<\/li>\n<li>Armario.<\/li>\n<li>Red.<\/li>\n<\/ol>\n<p>Una descripci\u00f3n m\u00e1s detallada de los tipos de planos y ejemplos la podemos encontrar <span style=\"color: #0000ff;\"><a href=\"https:\/\/controlreal.com\/es\/tipos-de-planos-electricos\/\">aqu\u00ed<\/a><\/span>.<\/p>\n<h2><strong>Formatos.<\/strong><\/h2>\n<p style=\"text-align: justify;\">Cuando se realiza un plano el\u00e9ctrico uno de los aspectos que se debe tomar en cuenta es el tama\u00f1o de papel empleado, por regla general se trata de ajustar el plano al tama\u00f1o m\u00e1s c\u00f3modo para el usuario final. El cuadro siguiente presenta la serie de formatos utilizados en proyectos de instalaciones el\u00e9ctricas, las dimensiones de cada uno de los formatos y los m\u00e1rgenes que deben tener. Estas dimensiones ha sido tomadas de DIN y su uso se ha generalizado a nivel mundial.<\/p>\n<table>\n<tbody>\n<tr>\n<td rowspan=\"2\" width=\"106\">\n<p style=\"text-align: center;\"><strong>FORMATO<\/strong><\/p>\n<\/td>\n<td style=\"text-align: center;\" rowspan=\"2\" width=\"137\"><strong>DIMENSIONES<\/strong><strong>(mm)<\/strong><\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"194\"><strong>MARGENES<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"116\"><strong>IZQUIERDO<\/strong><\/td>\n<td style=\"text-align: center;\" width=\"78\"><strong>OTROS<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"106\">\n<p style=\"text-align: center;\">A0<\/p>\n<\/td>\n<td style=\"text-align: center;\" width=\"137\">1189X841<\/td>\n<td style=\"text-align: center;\" width=\"116\">35<\/td>\n<td style=\"text-align: center;\" width=\"78\">10<\/td>\n<\/tr>\n<tr>\n<td width=\"106\">\n<p style=\"text-align: center;\">A1<\/p>\n<\/td>\n<td style=\"text-align: center;\" width=\"137\">594X841<\/td>\n<td style=\"text-align: center;\" width=\"116\">30<\/td>\n<td style=\"text-align: center;\" width=\"78\">10<\/td>\n<\/tr>\n<tr>\n<td width=\"106\">\n<p style=\"text-align: center;\">A2<\/p>\n<\/td>\n<td style=\"text-align: center;\" width=\"137\">420X594<\/td>\n<td style=\"text-align: center;\" width=\"116\">30<\/td>\n<td style=\"text-align: center;\" width=\"78\">10<\/td>\n<\/tr>\n<tr>\n<td width=\"106\">\n<p style=\"text-align: center;\">A3<\/p>\n<\/td>\n<td style=\"text-align: center;\" width=\"137\">297X420<\/td>\n<td style=\"text-align: center;\" width=\"116\">30<\/td>\n<td style=\"text-align: center;\" width=\"78\">10<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"106\">\n<p style=\"text-align: center;\">A4<\/p>\n<\/td>\n<td style=\"text-align: center;\" width=\"137\">210X297<\/td>\n<td style=\"text-align: center;\" width=\"116\">30<\/td>\n<td width=\"78\">\n<p style=\"text-align: center;\">10<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>La siguiente figura muestra un esquema donde se pueden observar los diferentes formatos.<\/p>\n<div id=\"attachment_268\" style=\"width: 427px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Formatos.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-268\" class=\"wp-image-268 size-full\" src=\"http:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Formatos.png\" alt=\"Relaci\u00f3n entre los diferentes formatos del papel. para planos el\u00e9ctricos\" width=\"417\" height=\"580\" srcset=\"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Formatos.png 417w, https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Formatos-216x300.png 216w\" sizes=\"auto, (max-width: 417px) 100vw, 417px\" \/><\/a><p id=\"caption-attachment-268\" class=\"wp-caption-text\">Relaci\u00f3n entre los diferentes formatos del papel. para planos el\u00e9ctricos<\/p><\/div>\n<p>Adem\u00e1s del diagrama el plano tiene un membrete, unas coordenadas y un logotipo.<\/p>\n<h3><strong>Membrete:<\/strong><\/h3>\n<p>En el membrete o cajet\u00edn se coloca toda la informaci\u00f3n referente al plano, esta incluye:<\/p>\n<ul>\n<li>Fecha de elaboraci\u00f3n.<\/li>\n<li>Fecha de modificaci\u00f3n.<\/li>\n<li>Nombre del dibujante.<\/li>\n<li>Escala<\/li>\n<li>N\u00famero de revisi\u00f3n.<\/li>\n<li>Descripci\u00f3n del plano.<\/li>\n<li>N\u00famero del plano.<\/li>\n<li>Cantidad total de hoja que tiene el conjunto de planos.<\/li>\n<li>Nombre de la empresa en donde se encuentra el sistema que describe el plano.<\/li>\n<li>Nombre de la empresa que elabor\u00f3 el plano.<\/li>\n<\/ul>\n<p>Su ubicaci\u00f3n, generalmente va en la parte inferior del plano, aunque tambi\u00e9n se puede colocar en la parte derecha o izquierda.<\/p>\n<h3><strong>Logotipo<\/strong><\/h3>\n<p>Esta secci\u00f3n es opcional y corresponde al logotipo de la empresa que dise\u00f1o el plano<\/p>\n<h3><strong>Coordenadas para ubicaci\u00f3n:<\/strong><\/h3>\n<p style=\"text-align: justify;\">Facilita la ubicaci\u00f3n r\u00e1pida de un elemento en una p\u00e1gina especifica del plano que se encuentra referenciado en otra; para ello se divide el plano en cuadriculas o en franjas. A este sistema tambi\u00e9n se le denomina <span style=\"color: #0000ff;\"><a href=\"https:\/\/controlreal.com\/es\/referencia-cruzada\/\">referencia cruzada<\/a><\/span>.<\/p>\n<p style=\"text-align: justify;\"><strong>Divisi\u00f3n en cuadriculas<\/strong>: utiliza un n\u00fameros en los bordes horizontales y una letras en los bordes verticales, o viceversa, que divide el plano en cuadros, cada cuadro est\u00e1 identificado por una letra y un n\u00famero, 5E por ejemplo.<\/p>\n<p style=\"text-align: justify;\"><strong>Divisi\u00f3n por franjas<\/strong>. S\u00f3lo utiliza n\u00fameros en los bordes horizontales, esto hace que el plano se divida en franjas que permite ubicar un elemento en el plano.<\/p>\n<p>La figura siguiente figura muestra un formato de dibujo con sus diferentes partes:<\/p>\n<div id=\"attachment_269\" style=\"width: 659px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Membrete.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-269\" class=\"wp-image-269 size-full\" src=\"http:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Membrete.png\" alt=\"Membrete\" width=\"649\" height=\"454\" srcset=\"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Membrete.png 649w, https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Membrete-300x210.png 300w\" sizes=\"auto, (max-width: 649px) 100vw, 649px\" \/><\/a><p id=\"caption-attachment-269\" class=\"wp-caption-text\">Partes del formato para el plano.<\/p><\/div>\n<h2><strong>Ejemplos<\/strong><\/h2>\n<p>A continuaci\u00f3n se muestran dos ejemplos de planos el\u00e9ctricos similares, el primero usa norma europea (IEC\/DIN), y el segundo usa norma americana (ANSI). En ambos planos se muestra la parte de potencia y mando de un motor trif\u00e1sico AC.<\/p>\n<div id=\"attachment_267\" style=\"width: 1017px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-267\" class=\"wp-image-267 size-full\" src=\"http:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor.png\" alt=\"Plano en norma europea\" width=\"1007\" height=\"699\" srcset=\"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor.png 1007w, https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor-300x208.png 300w\" sizes=\"auto, (max-width: 1007px) 100vw, 1007px\" \/><\/a><p id=\"caption-attachment-267\" class=\"wp-caption-text\">Plano en norma europea<\/p><\/div>\n<div id=\"attachment_270\" style=\"width: 1671px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Motor-ANSI.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-270\" class=\"wp-image-270 size-full\" src=\"http:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Motor-ANSI.png\" alt=\"Motor ANSI\" width=\"1661\" height=\"1222\" srcset=\"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Motor-ANSI.png 1661w, https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Motor-ANSI-300x221.png 300w, https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Motor-ANSI-1024x753.png 1024w, https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Motor-ANSI-1170x861.png 1170w\" sizes=\"auto, (max-width: 1661px) 100vw, 1661px\" \/><\/a><p id=\"caption-attachment-270\" class=\"wp-caption-text\">Plano en norma americana<\/p><\/div>\n<h2>Referencias<\/h2>\n<p>INTERNATIONAL ELECTROTECHNICAL COMMISSION <strong>IEC 61082: PREPARATION OF DOCUMENTS USED IN ELECTROTECHNOLOGY, a\u00f1o de publicacion 25 de Enero de 2002<\/strong><\/p>\n<div align=\"center\">\n<a  href=\"https:\/\/www.udemy.com\/lectura-e-interpretacion-de-planos-electricos\/?couponCode=LIPOFERTA\" target=\"_blank\"> Puedes obtener mucha m\u00e1s informaci\u00f3n acerca de lectura e interpretaci\u00f3n de planos el\u00e9ctricos en el siguiente entrenamiento de Udemy. 45% de descuento, haciendo click aqu\u00ed. SOLO POR TIEMPO LIMITADO.<br \/>\n<img decoding=\"async\" src=\"http:\/\/controlreal.com\/es\/cr-content\/uploads\/2019\/04\/Animacion.gif\" alt=\"LIP\" style=\"width:600px;height:404px;\"><br \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En los diagramas o planos el\u00e9ctricos se representan de forma gr\u00e1fica los componentes, y su interconexi\u00f3n, en una instalaci\u00f3n el\u00e9ctrica. El uso de planos el\u00e9ctricos est\u00e1 basado en est\u00e1ndares creados por diferentes organizaciones internacionales. Su uso permite la construcci\u00f3n y&#8230;<br \/><a class=\"read-more-button\" href=\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[37,35,42,36,40,44,34,43],"class_list":["post-281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-planos","tag-ansi","tag-din","tag-formato","tag-iec","tag-logotipo","tag-membrete","tag-planos-electricos","tag-referencia-cruzada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Planos El\u00e9ctricos. Lectura e interpretaci\u00f3n. - Control Real Espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"Planos El\u00e9ctricos. S\u00edmbolos. Nomenclatura. Tipos de planos el\u00e9ctricos. Normas. Formatos. Membrete. Referencia cruzada. Ejemplos. Normas americana y europea.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Planos El\u00e9ctricos. Lectura e interpretaci\u00f3n. - Control Real Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"Planos El\u00e9ctricos. S\u00edmbolos. Nomenclatura. Tipos de planos el\u00e9ctricos. Normas. Formatos. Membrete. Referencia cruzada. Ejemplos. Normas americana y europea.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Control Real Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-25T17:13:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-18T22:31:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1007\" \/>\n\t<meta property=\"og:image:height\" content=\"699\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"miguel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ControlReal\" \/>\n<meta name=\"twitter:site\" content=\"@ControlReal\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"miguel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/\"},\"author\":{\"name\":\"miguel\",\"@id\":\"https:\/\/controlreal.com\/es\/#\/schema\/person\/465d0f405499ce9988d4159aea1415fe\"},\"headline\":\"Planos El\u00e9ctricos. Lectura e interpretaci\u00f3n.\",\"datePublished\":\"2015-06-25T17:13:18+00:00\",\"dateModified\":\"2019-05-18T22:31:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/\"},\"wordCount\":1291,\"commentCount\":36,\"publisher\":{\"@id\":\"https:\/\/controlreal.com\/es\/#\/schema\/person\/465d0f405499ce9988d4159aea1415fe\"},\"image\":{\"@id\":\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor.png\",\"keywords\":[\"ANSI\",\"DIN\",\"formato\",\"IEC\",\"logotipo\",\"membrete\",\"planos el\u00e9ctricos\",\"referencia cruzada\"],\"articleSection\":[\"planos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/\",\"url\":\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/\",\"name\":\"Planos El\u00e9ctricos. Lectura e interpretaci\u00f3n. - Control Real Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\/\/controlreal.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor.png\",\"datePublished\":\"2015-06-25T17:13:18+00:00\",\"dateModified\":\"2019-05-18T22:31:52+00:00\",\"description\":\"Planos El\u00e9ctricos. S\u00edmbolos. Nomenclatura. Tipos de planos el\u00e9ctricos. Normas. Formatos. Membrete. Referencia cruzada. Ejemplos. Normas americana y europea.\",\"breadcrumb\":{\"@id\":\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#primaryimage\",\"url\":\"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor.png\",\"contentUrl\":\"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor.png\",\"width\":1007,\"height\":699},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/controlreal.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"planos\",\"item\":\"https:\/\/controlreal.com\/es\/category\/planos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Planos El\u00e9ctricos. Lectura e interpretaci\u00f3n.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/controlreal.com\/es\/#website\",\"url\":\"https:\/\/controlreal.com\/es\/\",\"name\":\"Control Real Espa\u00f1ol\",\"description\":\"Tips y descargas para control de procesos, automatizaci\u00f3n y PLC\",\"publisher\":{\"@id\":\"https:\/\/controlreal.com\/es\/#\/schema\/person\/465d0f405499ce9988d4159aea1415fe\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/controlreal.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/controlreal.com\/es\/#\/schema\/person\/465d0f405499ce9988d4159aea1415fe\",\"name\":\"miguel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/controlreal.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6628fbbc38973f2763d1c8cd2856b93d71d35ad70a682b890dcb83960ac8c629?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6628fbbc38973f2763d1c8cd2856b93d71d35ad70a682b890dcb83960ac8c629?s=96&d=mm&r=g\",\"caption\":\"miguel\"},\"logo\":{\"@id\":\"https:\/\/controlreal.com\/es\/#\/schema\/person\/image\/\"},\"description\":\"Ingeniero Electr\u00f3nico mas de 23 a\u00f1os de experiencia en automatizaci\u00f3n industrial, docencia e investigaci\u00f3n.\",\"url\":\"https:\/\/controlreal.com\/es\/author\/miguel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Planos El\u00e9ctricos. Lectura e interpretaci\u00f3n. - Control Real Espa\u00f1ol","description":"Planos El\u00e9ctricos. S\u00edmbolos. Nomenclatura. Tipos de planos el\u00e9ctricos. Normas. Formatos. Membrete. Referencia cruzada. Ejemplos. Normas americana y europea.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/","og_locale":"es_ES","og_type":"article","og_title":"Planos El\u00e9ctricos. Lectura e interpretaci\u00f3n. - Control Real Espa\u00f1ol","og_description":"Planos El\u00e9ctricos. S\u00edmbolos. Nomenclatura. Tipos de planos el\u00e9ctricos. Normas. Formatos. Membrete. Referencia cruzada. Ejemplos. Normas americana y europea.","og_url":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/","og_site_name":"Control Real Espa\u00f1ol","article_published_time":"2015-06-25T17:13:18+00:00","article_modified_time":"2019-05-18T22:31:52+00:00","og_image":[{"width":1007,"height":699,"url":"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor.png","type":"image\/png"}],"author":"miguel","twitter_card":"summary_large_image","twitter_creator":"@ControlReal","twitter_site":"@ControlReal","twitter_misc":{"Escrito por":"miguel","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#article","isPartOf":{"@id":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/"},"author":{"name":"miguel","@id":"https:\/\/controlreal.com\/es\/#\/schema\/person\/465d0f405499ce9988d4159aea1415fe"},"headline":"Planos El\u00e9ctricos. Lectura e interpretaci\u00f3n.","datePublished":"2015-06-25T17:13:18+00:00","dateModified":"2019-05-18T22:31:52+00:00","mainEntityOfPage":{"@id":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/"},"wordCount":1291,"commentCount":36,"publisher":{"@id":"https:\/\/controlreal.com\/es\/#\/schema\/person\/465d0f405499ce9988d4159aea1415fe"},"image":{"@id":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#primaryimage"},"thumbnailUrl":"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor.png","keywords":["ANSI","DIN","formato","IEC","logotipo","membrete","planos el\u00e9ctricos","referencia cruzada"],"articleSection":["planos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/","url":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/","name":"Planos El\u00e9ctricos. Lectura e interpretaci\u00f3n. - Control Real Espa\u00f1ol","isPartOf":{"@id":"https:\/\/controlreal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#primaryimage"},"image":{"@id":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#primaryimage"},"thumbnailUrl":"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor.png","datePublished":"2015-06-25T17:13:18+00:00","dateModified":"2019-05-18T22:31:52+00:00","description":"Planos El\u00e9ctricos. S\u00edmbolos. Nomenclatura. Tipos de planos el\u00e9ctricos. Normas. Formatos. Membrete. Referencia cruzada. Ejemplos. Normas americana y europea.","breadcrumb":{"@id":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#primaryimage","url":"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor.png","contentUrl":"https:\/\/controlreal.com\/es\/cr-content\/uploads\/2015\/06\/Plano-motor.png","width":1007,"height":699},{"@type":"BreadcrumbList","@id":"https:\/\/controlreal.com\/es\/planos-electricos-lectura-interpretacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/controlreal.com\/es\/"},{"@type":"ListItem","position":2,"name":"planos","item":"https:\/\/controlreal.com\/es\/category\/planos\/"},{"@type":"ListItem","position":3,"name":"Planos El\u00e9ctricos. Lectura e interpretaci\u00f3n."}]},{"@type":"WebSite","@id":"https:\/\/controlreal.com\/es\/#website","url":"https:\/\/controlreal.com\/es\/","name":"Control Real Espa\u00f1ol","description":"Tips y descargas para control de procesos, automatizaci\u00f3n y PLC","publisher":{"@id":"https:\/\/controlreal.com\/es\/#\/schema\/person\/465d0f405499ce9988d4159aea1415fe"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/controlreal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/controlreal.com\/es\/#\/schema\/person\/465d0f405499ce9988d4159aea1415fe","name":"miguel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/controlreal.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6628fbbc38973f2763d1c8cd2856b93d71d35ad70a682b890dcb83960ac8c629?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6628fbbc38973f2763d1c8cd2856b93d71d35ad70a682b890dcb83960ac8c629?s=96&d=mm&r=g","caption":"miguel"},"logo":{"@id":"https:\/\/controlreal.com\/es\/#\/schema\/person\/image\/"},"description":"Ingeniero Electr\u00f3nico mas de 23 a\u00f1os de experiencia en automatizaci\u00f3n industrial, docencia e investigaci\u00f3n.","url":"https:\/\/controlreal.com\/es\/author\/miguel\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/controlreal.com\/es\/wp-json\/wp\/v2\/posts\/281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/controlreal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/controlreal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/controlreal.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/controlreal.com\/es\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":18,"href":"https:\/\/controlreal.com\/es\/wp-json\/wp\/v2\/posts\/281\/revisions"}],"predecessor-version":[{"id":968,"href":"https:\/\/controlreal.com\/es\/wp-json\/wp\/v2\/posts\/281\/revisions\/968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/controlreal.com\/es\/wp-json\/wp\/v2\/media\/267"}],"wp:attachment":[{"href":"https:\/\/controlreal.com\/es\/wp-json\/wp\/v2\/media?parent=281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/controlreal.com\/es\/wp-json\/wp\/v2\/categories?post=281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/controlreal.com\/es\/wp-json\/wp\/v2\/tags?post=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}